﻿{"id":3972,"date":"2024-10-10T14:42:02","date_gmt":"2024-10-10T04:42:02","guid":{"rendered":"https:\/\/ambcanberra.esteri.it\/?p=3972"},"modified":"2024-10-10T14:47:30","modified_gmt":"2024-10-10T04:47:30","slug":"apertura-straordinaria-per-la-xx-giornata-del-contemporaneo-12-ottobre-2024","status":"publish","type":"post","link":"https:\/\/ambcanberra.esteri.it\/en\/news\/dall_ambasciata\/2024\/10\/apertura-straordinaria-per-la-xx-giornata-del-contemporaneo-12-ottobre-2024\/","title":{"rendered":"Apertura straordinaria per la XX Giornata del Contemporaneo \u2013 12 Ottobre 2024"},"content":{"rendered":"<p style=\"text-align: justify;\">Il prossimo <strong>12\u00a0ottobre<\/strong>\u00a0si terr\u00e0 la<strong> XX Giornata del Contemporaneo in Italia, promossa da <a href=\"https:\/\/www.amaci.org\/\">AMACI<\/a><\/strong>\u00a0\u2013 Associazione dei Musei d\u2019Arte Contemporanea Italiani che, insieme a musei, fondazioni, istituzioni pubbliche e private, gallerie, studi e spazi d\u2019artista, promuove la rete del contemporaneo a livello sia nazionale sia internazionale. Come nelle precedenti edizioni, per la <strong>rete estera delle Ambasciate, Consolati e Istituti Italiani di Cultura, la\u00a0Giornata del Contemporaneo \u2013 Italian Contemporary Art<\/strong>\u00a0avr\u00e0 una durata pi\u00f9 estesa,\u00a0<strong>da domenica 6 ottobre a sabato 12 ottobre 2024.<br \/>\n<\/strong><br \/>\nLa\u00a0<strong>promozione dell\u2019arte e degli artisti contemporanei italiani<\/strong>\u00a0(dei musei e dei luoghi del contemporaneo italiani e delle professionalit\u00e0 che compongono il nostro sistema del contemporaneo) \u00e8 una delle attivit\u00e0 prioritarie del Ministero degli Affari Esteri e della sua rete estera, portata avanti attraverso l\u2019organizzazione di mostre, eventi, presentazioni, scambi e residenze d\u2019artista. La manifestazione si avvale, infatti, oltre che del sostegno della\u00a0Direzione Generale Creativit\u00e0 Contemporanea del Ministero della Cultura\u00a0e\u00a0della collaborazione della\u00a0<strong>Direzione Generale per la Diplomazia Pubblica e Culturale del Ministero degli Affari Esteri e della Cooperazione Internazionale<\/strong><strong>.<\/strong><\/p>\n<p style=\"text-align: justify;\">La visita straordinaria alla Collezione e ai principali ambienti del Palazzo della Farnesina avr\u00e0 un turno di visita dalle <strong>ore 10.0-11.30<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Le prenotazioni per questo evento sono aperte fino a <strong>gioved\u00ec 10 ottobre.<\/strong> La prenotazione \u00e8 personale e non cedibile, una volta effettuata non \u00e8 pi\u00f9 possibile effettuare modifiche.<\/p>\n<p style=\"text-align: justify;\">Per cancellazioni o qualsiasi problema scrivere a\u00a0<strong>dgdp.unic.colfarnesina@esteri.it<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Per saperne di pi\u00f9 su questo evento: <a href=\"http:\/\/www.amaci.org\">www.amaci.org<\/a><br \/>\nPer visitare la Collezione d&#8217;Arte della Farnesina: <a href=\"https:\/\/collezionefarnesina.esteri.it\">https:\/\/collezionefarnesina.esteri.it<\/a><\/p>\n<figure id=\"attachment_3961\" aria-describedby=\"caption-attachment-3961\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"img-fluid wp-image-3961 size-medium\" src=\"https:\/\/ambcanberra.esteri.it\/wp-content\/uploads\/2024\/10\/Tomaso-Binga-per-la-Ventesima-Giornata-del-Contemporaneo-Donna-in-gabbia-1975-2024-730x600-1-300x247.jpg\" alt=\"\" width=\"300\" height=\"247\" srcset=\"https:\/\/ambcanberra.esteri.it\/wp-content\/uploads\/2024\/10\/Tomaso-Binga-per-la-Ventesima-Giornata-del-Contemporaneo-Donna-in-gabbia-1975-2024-730x600-1-300x247.jpg 300w, https:\/\/ambcanberra.esteri.it\/wp-content\/uploads\/2024\/10\/Tomaso-Binga-per-la-Ventesima-Giornata-del-Contemporaneo-Donna-in-gabbia-1975-2024-730x600-1.jpg 730w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-3961\" class=\"wp-caption-text\"><em>\u201cDonna in gabbia (1975\/2024)\u201d is the image presented by Tomaso Binga for the 20th edition. The artist\u2019s head in a canary cage, fed by male hands, symbolizes women\u2019s restrictive subordination and broader social inequalities. The cage represents barriers to freedom and the need for greater awareness and emancipation.<\/em><\/figcaption><\/figure>\n<p style=\"text-align: left;\"><em>Credits: Tomaso Binga per la Ventesima Giornata del Contemporaneo 2024<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"Il prossimo 12\u00a0ottobre\u00a0si terr\u00e0 la XX Giornata del Contemporaneo in Italia, promossa da AMACI\u00a0\u2013 Associazione dei Musei d\u2019Arte Contemporanea Italiani che, insieme a musei, fondazioni, istituzioni pubbliche e private, gallerie, studi e spazi d\u2019artista, promuove la rete del contemporaneo a livello sia nazionale sia internazionale. Come nelle precedenti edizioni, per la rete estera delle Ambasciate, [&hellip;]","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-3972","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/posts\/3972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/comments?post=3972"}],"version-history":[{"count":1,"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/posts\/3972\/revisions"}],"predecessor-version":[{"id":3973,"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/posts\/3972\/revisions\/3973"}],"wp:attachment":[{"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/media?parent=3972"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambcanberra.esteri.it\/en\/wp-json\/wp\/v2\/tags?post=3972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}